{"id":3746,"date":"2015-10-08T17:48:19","date_gmt":"2015-10-08T21:48:19","guid":{"rendered":"https:\/\/www.mencare.org\/?p=3746"},"modified":"2015-10-08T17:53:18","modified_gmt":"2015-10-08T21:53:18","slug":"i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka","status":"publish","type":"post","link":"https:\/\/www.mencare.org\/pt\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/","title":{"rendered":"\u201cEu entendi que minha vida tinha que mudar\u201d: hist\u00f3rias da MenCare do Sri Lanka"},"content":{"rendered":"<p><a href=\"#Ramesh\">A hist\u00f3ria de Ramesh<\/a> | <a href=\"#Sivakumar\">A hist\u00f3ria de Sivakumar<\/a> | <a href=\"#Pushparajan\">A hist\u00f3ria do Sr. Pushparajan<\/a> | <a href=\"#Sathiskumar\">A hist\u00f3ria de Sathiskumar<\/a><\/p>\n<h2>Hist\u00f3rias do Programa de Desenvolvimento da \u00c1rea de Ambagamuwa<\/h2>\n<p><em>Vis\u00e3o Mundial Lanka&#039;s <a href=\"http:\/\/www.wvi.org\/sri-lanka\/programme-locations\" target=\"_blank\">Programa de Desenvolvimento da \u00c1rea Ambagamuwa (ADP)<\/a> vem realizando a programa\u00e7\u00e3o MenCare desde 2012, melhorando as vidas de crian\u00e7as e fam\u00edlias na comunidade de planta\u00e7\u00f5es do Sri Lanka. Este m\u00eas, o ADP de Ambagamuwa compartilhou hist\u00f3rias de tr\u00eas pais que participaram do programa.<\/em><\/p>\n<h3><a id=\"Ramesh\"><\/a>A hist\u00f3ria de Ramesh<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3750\" src=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh.jpg\" alt=\"Ramesh and his family\" width=\"300\" height=\"300\" \/>Ramesh, um pai de quatro filhos de 30 anos, casou-se com a trabalhadora rural Nirmala Devi aos 22 anos. Ap\u00f3s o casamento, Ramesh viajou para Colombo \u2013 a 150 quil\u00f4metros de sua casa \u2013 em busca de emprego. Devido \u00e0 dist\u00e2ncia e \u00e0s restri\u00e7\u00f5es de seu novo emprego, Ramesh n\u00e3o conseguia voltar para casa regularmente. Ele come\u00e7ou a beber muito com amigos e a visitar sua fam\u00edlia com ainda menos frequ\u00eancia. Quando ele voltava para casa, ele frequentemente se tornava violento com sua esposa e desconsiderava seus filhos e suas necessidades acad\u00eamicas.<\/p>\n<p>Em 2013, Ramesh se juntou a um grupo de pais MenCare conduzido pelo Ambagamuwa ADP. Ele participou do programa por cerca de seis meses e, por meio dos grupos, come\u00e7ou a perceber a import\u00e2ncia de se envolver mais nas vidas de sua esposa e filhos de maneiras equitativas e n\u00e3o violentas.<\/p>\n<p>Nirmala Devi disse que o novo compromisso do marido com a n\u00e3o viol\u00eancia e a participa\u00e7\u00e3o em casa ajudou toda a fam\u00edlia:<\/p>\n<p>\u201cT\u00ednhamos muitos problemas em nossa fam\u00edlia. Todos eles mudaram quando meu marido come\u00e7ou a frequentar as aulas do MenCare\u201d, diz Nirmala Devi. \u201cPrimeiro, ele largou o emprego em Colombo e encontrou um emprego na propriedade. Ele parou de reclamar e brigar comigo sobre minhas defici\u00eancias. Em vez disso, ele se apresentou para me ajudar com o trabalho dom\u00e9stico, como cozinhar, lavar roupas e cuidar das crian\u00e7as. Sua presen\u00e7a em casa trouxe alegria e felicidade para minha fam\u00edlia. Meus filhos ficaram muito felizes em t\u00ea-lo em casa.\u201d<\/p>\n<p>Ramesh tamb\u00e9m reconhece que sua mudan\u00e7a o tornou um pai melhor, melhorou seu relacionamento com sua esposa e aumentou sua pr\u00f3pria felicidade.<\/p>\n<p>\u201cParei de consumir bebidas alco\u00f3licas, exceto em \u00e9pocas de festas ou casamentos\u201d, diz Ramesh. \u201cAntes, eu costumava gastar muito dinheiro com \u00e1lcool. Mas agora posso gast\u00e1-lo para suprir as necessidades das crian\u00e7as.<\/p>\n<p>\u201cAgora consigo entender os problemas pelos quais minha esposa passa. Antes, eu s\u00f3 reclamava e brigava com ela, pois sentia que ela era a culpada por todos os problemas. Mas agora eu a ajudo a cuidar das crian\u00e7as e a fazer o trabalho dom\u00e9stico. Resolvemos nossos problemas familiares juntos. Sinto que as li\u00e7\u00f5es que aprendi no programa MenCare foram muito importantes para mim. Eu n\u00e3o era um bom pai antes. Mas agora sinto que sou um bom pai. Amo muito minha fam\u00edlia.\u201d<\/p>\n<h3><a id=\"Sivakumar\"><\/a>A hist\u00f3ria de Sivakumar<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3751\" src=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Balasubramanium-Sivakumar.jpg\" alt=\"Sivakumar and his family\" width=\"300\" height=\"300\" \/>Sivakumar \u00e9 um trabalhador rural que se casou aos 24 anos. Ap\u00f3s um ano de casamento, ele sofreu queimaduras graves em um acidente que deixou seu rosto permanentemente marcado. Incapaz de lidar com o trauma do acidente e sua desfigura\u00e7\u00e3o f\u00edsica, Sivakumar come\u00e7ou a beber em excesso e a usar viol\u00eancia verbal e f\u00edsica contra sua esposa, que deixou o relacionamento abusivo.<\/p>\n<p>Sivakumar se casou novamente depois de cinco anos, e come\u00e7ou a usar viol\u00eancia contra sua segunda esposa Sakunthala. Sakunthala permaneceu com Sivakumar, apesar da insist\u00eancia de seus pais para que ela voltasse para casa.<\/p>\n<p>Enquanto isso, Sivakumar teve a oportunidade de se juntar a um grupo de pais MenCare conduzido pelo ADP de Ambagamuwa. Nos grupos, ele aprendeu sobre a import\u00e2ncia da participa\u00e7\u00e3o ativa no cuidado infantil; distribui\u00e7\u00e3o equitativa das responsabilidades dom\u00e9sticas; promo\u00e7\u00e3o da igualdade de g\u00eanero dentro da fam\u00edlia e da comunidade; relacionamentos saud\u00e1veis e n\u00e3o violentos; sa\u00fade e direitos sexuais e reprodutivos; modera\u00e7\u00e3o do consumo de \u00e1lcool; e responsabilidade social. A experi\u00eancia o levou a transformar suas atitudes e comportamentos:<\/p>\n<p>\u201cFoi somente depois de participar do programa MenCare que entendi que minha vida tinha que mudar. Eu n\u00e3o me importava com minha esposa e com a crian\u00e7a antes\u201d, disse Sivakumar. \u201cEu n\u00e3o pensava no futuro do meu filho.\u201d<\/p>\n<p>\u201cMas agora ajudo minha esposa\u201d, ele explicou. \u201cEu cuido da minha filha enquanto ela trabalha na propriedade. Tamb\u00e9m consigo economizar dinheiro para o futuro da minha filha. Abri uma conta banc\u00e1ria e deposito algum dinheiro mensalmente para ela.\u201d<\/p>\n<p>Sakunthala tamb\u00e9m atesta a mudan\u00e7a de seu marido:<\/p>\n<p>\u201cNos dias em que meu marido costumava receber, ele chegava b\u00eabado em casa\u201d, ela disse. \u201cMas agora, quando recebemos o sal\u00e1rio, n\u00f3s dois vamos \u00e0 cidade para comprar o que precisamos para o resto dos dias. Damos \u00e0 nossa filha o que ela precisa. Meu marido faz o trabalho dom\u00e9stico na minha aus\u00eancia e cuida dela. Estou muito feliz com sua mudan\u00e7a de comportamento. Minha \u00fanica esperan\u00e7a \u00e9 dar uma boa educa\u00e7\u00e3o para minha filha.\u201d<\/p>\n<h3><a id=\"Pushparajan\"><\/a>A hist\u00f3ria do Sr. Pushparajan<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3749\" src=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Mr-Pushparajan.jpg\" alt=\"Mr. Pushparajan and his family\" width=\"300\" height=\"300\" \/>O Sr. Pushparajan \u00e9 casado com Parameswary h\u00e1 seis anos. O casal tem dois filhos \u2013 uma menina de seis anos e um menino de tr\u00eas anos. O Sr. Pushparajan trabalha como alfaiate e sua esposa sustenta o neg\u00f3cio deles, que \u00e9 administrado de casa.<\/p>\n<p>Antes de o Sr. Pushparajan ingressar no programa MenCare h\u00e1 dois anos, ele costumava beber e fumar excessivamente. Ele usava viol\u00eancia contra Parameswary e seus filhos quando eles discordavam dele. Ele n\u00e3o participava da alimenta\u00e7\u00e3o das crian\u00e7as ou as ajudava com o dever de casa, e acreditava que era responsabilidade da esposa cozinhar, realizar tarefas dom\u00e9sticas e cuidar das crian\u00e7as.<\/p>\n<p>O programa MenCare levou a uma transforma\u00e7\u00e3o nas atitudes e comportamentos do Sr. Pushparajan em rela\u00e7\u00e3o \u00e0 sua fam\u00edlia. Ele aprendeu a import\u00e2ncia da n\u00e3o viol\u00eancia em seu relacionamento com sua esposa e filhos, e adotou estrat\u00e9gias de comunica\u00e7\u00e3o positivas e livres de viol\u00eancia para resolver conflitos. Al\u00e9m de compartilhar a tomada de decis\u00f5es dom\u00e9sticas, cuidados com as crian\u00e7as e responsabilidades dom\u00e9sticas com Parameswary, o Sr. Pushparajan tamb\u00e9m aprendeu a compartilhar a tomada de decis\u00f5es financeiras com sua esposa, e juntos eles reduziram despesas desnecess\u00e1rias e aumentaram a poupan\u00e7a.<\/p>\n<p>Por meio dessas mudan\u00e7as, o Sr. Pushparajan encontrou felicidade e satisfa\u00e7\u00e3o com sua fam\u00edlia em casa, melhorou seu relacionamento com seus amigos e vizinhos e se tornou um modelo positivo para outros na comunidade seguirem. De fato, a maioria dos outros pais no grupo MenCare do Sr. Pushparajan fizeram mudan\u00e7as semelhantes, ele diz, indicando o sucesso do programa.<\/p>\n<h2>Hist\u00f3rias do Programa de Desenvolvimento da \u00c1rea de Nuwara Eliya<\/h2>\n<p><em>Vis\u00e3o Mundial Lanka&#039;s <a href=\"http:\/\/www.wvi.org\/sri-lanka\/programme-locations\" target=\"_blank\">Programa de Desenvolvimento da \u00c1rea Nuwara Eliya (ADP)<\/a> vem realizando a programa\u00e7\u00e3o MenCare desde janeiro de 2015, trabalhando com homens e suas fam\u00edlias na comunidade de planta\u00e7\u00f5es do Sri Lanka para promover a igualdade de g\u00eanero e o bem-estar familiar. Em setembro, o Nuwara Eliya ADP compartilhou a hist\u00f3ria de um pai que participou do programa.<\/em><\/p>\n<h3><a id=\"Sathiskumar\"><\/a>A hist\u00f3ria de Sathiskumar<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3752\" src=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Sathiskumar.jpg\" alt=\"Sathiskumar and his family\" width=\"300\" height=\"300\" \/>Sathiskumar, que tem 29 anos, tem um filho de nove meses com sua esposa Sathyavani. Por meio da programa\u00e7\u00e3o MenCare no Nuwara Eliya ADP, Sathiskumar aprendeu a import\u00e2ncia de compartilhar o trabalho de cuidado e economizar para o futuro de seu filho.<\/p>\n<p>\u201cEu costumava gastar \u20a8 600 [US$ 4,60] de cada vez para consumir \u00e1lcool quando tinha dinheiro em m\u00e3os\u201d, disse Sathiskumar. \u201cDepois de participar das sess\u00f5es de paternidade, percebi que era ruim para minha vida familiar. Agora, reduzi meu consumo de \u00e1lcool e vou parar completamente muito em breve. Consegui aumentar a economia para meu filho de \u20a8 200 para \u20a8 400 por m\u00eas.\u201d<\/p>\n<p>\u201cCostum\u00e1vamos brigar quando discord\u00e1vamos em certos assuntos\u201d, Sathiskumar continuou. \u201cAgora n\u00e3o brigamos mais, e conversamos se houver algum problema. Eu cuido do meu filho quando minha esposa se envolve em outro trabalho em casa. N\u00f3s dois trabalhamos na planta\u00e7\u00e3o de ch\u00e1 como oper\u00e1rios. Eu costumava esperar que minha esposa voltasse do campo e preparasse o almo\u00e7o para mim. Mas agora eu preparo o almo\u00e7o sem esperar que ela venha cozinhar.\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p>Four fathers in Sri Lanka who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers&#8217; groups in their communities, in World Vision Lanka&#8217;s Ambagamuwa and Nuwara Eliya Area Development Programs.<\/p>","protected":false},"author":178,"featured_media":3753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[15,438,437,244,246,420],"class_list":["post-3746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-ambagamuwa-adp","tag-change","tag-nuwara-eliya-adp","tag-sri-lanka","tag-stories-of-change","tag-vaw","countries-sri-lanka"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;My life had to change&quot; - Stories from Sri Lanka - MenCare<\/title>\n<meta name=\"description\" content=\"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers&#039; groups.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mencare.org\/pt\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;My life had to change&quot; - Stories from Sri Lanka - MenCare\" \/>\n<meta property=\"og:description\" content=\"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers&#039; groups.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mencare.org\/pt\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/\" \/>\n<meta property=\"og:site_name\" content=\"MenCare\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-08T21:48:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-08T21:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-banner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RadishLab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RadishLab\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/\",\"url\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/\",\"name\":\"\\\"My life had to change\\\" - Stories from Sri Lanka - MenCare\",\"isPartOf\":{\"@id\":\"https:\/\/www.mencare.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg\",\"datePublished\":\"2015-10-08T21:48:19+00:00\",\"dateModified\":\"2015-10-08T21:53:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.mencare.org\/#\/schema\/person\/b9fee429ac8580ed216def21e04b2819\"},\"description\":\"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers' groups.\",\"breadcrumb\":{\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage\",\"url\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg\",\"contentUrl\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg\",\"width\":550,\"height\":400,\"caption\":\"Ramesh and his family\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mencare.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cI understood that my life had to change\u201d: MenCare stories from Sri Lanka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mencare.org\/#website\",\"url\":\"https:\/\/www.mencare.org\/\",\"name\":\"MenCare\",\"description\":\"A Global Fatherhood Campaign\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mencare.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mencare.org\/#\/schema\/person\/b9fee429ac8580ed216def21e04b2819\",\"name\":\"RadishLab\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mencare.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g\",\"caption\":\"RadishLab\"},\"url\":\"https:\/\/www.mencare.org\/pt\/author\/radishlab\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"My life had to change\" - Stories from Sri Lanka - MenCare","description":"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers' groups.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mencare.org\/pt\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/","og_locale":"pt_BR","og_type":"article","og_title":"\"My life had to change\" - Stories from Sri Lanka - MenCare","og_description":"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers' groups.","og_url":"http:\/\/www.mencare.org\/pt\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/","og_site_name":"MenCare","article_published_time":"2015-10-08T21:48:19+00:00","article_modified_time":"2015-10-08T21:53:18+00:00","og_image":[{"width":1200,"height":628,"url":"http:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-banner.jpg","type":"image\/jpeg"}],"author":"RadishLab","twitter_card":"summary_large_image","twitter_misc":{"Written by":"RadishLab","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/","url":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/","name":"\"My life had to change\" - Stories from Sri Lanka - MenCare","isPartOf":{"@id":"https:\/\/www.mencare.org\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage"},"image":{"@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg","datePublished":"2015-10-08T21:48:19+00:00","dateModified":"2015-10-08T21:53:18+00:00","author":{"@id":"https:\/\/www.mencare.org\/#\/schema\/person\/b9fee429ac8580ed216def21e04b2819"},"description":"Four Sri Lankan fathers who participated in MenCare describe the dramatic changes they made to their lives and relationships after joining fathers' groups.","breadcrumb":{"@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#primaryimage","url":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg","contentUrl":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/10\/Subramanium-Ramesh-feature.jpg","width":550,"height":400,"caption":"Ramesh and his family"},{"@type":"BreadcrumbList","@id":"http:\/\/www.mencare.org\/i-understood-that-my-life-had-to-change-mencare-stories-from-sri-lanka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mencare.org\/"},{"@type":"ListItem","position":2,"name":"\u201cI understood that my life had to change\u201d: MenCare stories from Sri Lanka"}]},{"@type":"WebSite","@id":"https:\/\/www.mencare.org\/#website","url":"https:\/\/www.mencare.org\/","name":"Cuidados com os homens","description":"Uma Campanha Global de Paternidade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mencare.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.mencare.org\/#\/schema\/person\/b9fee429ac8580ed216def21e04b2819","name":"RadishLab","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mencare.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01a869e9508babcb1c66b6b41356b4ef63d5326e5b27c38b27ed4a46b8e36b9f?s=96&d=mm&r=g","caption":"RadishLab"},"url":"https:\/\/www.mencare.org\/pt\/author\/radishlab\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts\/3746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/users\/178"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/comments?post=3746"}],"version-history":[{"count":5,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts\/3746\/revisions"}],"predecessor-version":[{"id":3757,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts\/3746\/revisions\/3757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/media\/3753"}],"wp:attachment":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/media?parent=3746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/categories?post=3746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/tags?post=3746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}