{"id":520,"date":"2014-04-24T00:00:48","date_gmt":"2014-04-24T00:00:48","guid":{"rendered":"https:\/\/www.mencare.org\/?p=520"},"modified":"2014-04-24T00:00:48","modified_gmt":"2014-04-24T00:00:48","slug":"amaza-incorporates-the-principles-of-mencare-in-its-storyline","status":"publish","type":"post","link":"https:\/\/www.mencare.org\/pt\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/","title":{"rendered":"A AMAZA incorpora os princ\u00edpios do MenCare em seu enredo"},"content":{"rendered":"<p><em>Compilado pela Community Media Trust para MenCare<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-521\" src=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg\" alt=\"A male character from AMAZA, the South African TV series\" width=\"400\" height=\"291\" srcset=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg 550w, https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo-300x218.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>AMAZA, que significa ondas em IsiXhosa, \u00e9 uma s\u00e9rie dram\u00e1tica juvenil sul-africana que vai ao ar \u00e0s segundas-feiras \u00e0s 20h30 na SABC 1. A s\u00e9rie de 13 partes se passa em uma rua pitoresca de Muizenberg que vai da orla da praia e do Surfer&#039;s Corner at\u00e9 South Pen, a faculdade local onde um grupo diversificado de estudantes aprende a lidar com legados culturais e hist\u00f3ricos que os moldam.<\/p>\n<p>A hist\u00f3ria leva o p\u00fablico em uma jornada de quatro personagens principais em seus vinte e poucos anos enquanto eles tentam dar sentido \u00e0s suas decis\u00f5es. Siyabonga Mayola (26) interpreta um jovem pai chamado Bongani Mapanga; Shamilla Miller interpreta Ayesha Ibrahim, uma esportista ansiosa lutando com seu amor pelo surfe e sua f\u00e9; Zikhona Mda (28) \u00e9 Thembi Kamva, uma tenaz estudante de jornalismo, enquanto Sean-Marco Vorster (23) interpreta um jovem e ambicioso surfista, Jaco du Toit.<\/p>\n<p>AMAZA \u00e9 uma produ\u00e7\u00e3o de desenvolvimento liderada por uma equipe inteira de <a href=\"http:\/\/www.cmt.org.za\/\" target=\"_blank\">Fundo de m\u00eddia comunit\u00e1ria<\/a>, provando que qualquer desafio com o suporte certo pode ser um sucesso. Lucilla Blankenberg, codiretora da AMAZA e diretora da CMT, d\u00e1 cr\u00e9dito ao elenco e \u00e0 equipe da AMAZA por sua transi\u00e7\u00e3o suave para a produ\u00e7\u00e3o da primeira s\u00e9rie dram\u00e1tica da CMT, o que significou parceria e consultoria com stakeholders espec\u00edficos sobre temas relacionados \u00e0 paternidade, perda de poder, gravidez na adolesc\u00eancia e assumir responsabilidades.<\/p>\n<p>Em AMAZA, um dos personagens, Bongani Mapanga, \u00e9 for\u00e7ado a encarar a realidade de ser pai bem cedo na vida. Seu papel sonda quest\u00f5es sobre ser pai; no entanto, al\u00e9m disso, seu personagem reflete sobre a hist\u00f3ria mais profunda de seu pr\u00f3prio pai ausente, influenciando como ele se v\u00ea e, al\u00e9m disso, como ele cuida de seu filho. A s\u00e9rie tamb\u00e9m despertou alguns coment\u00e1rios relevantes e instigantes sobre como os jovens sul-africanos est\u00e3o lidando com a quest\u00e3o dos pais ausentes. Usando principalmente o Facebook e o Twitter para envolver os jovens no tema, a maioria dos espectadores elogiou ver Bongani assumir a responsabilidade. Em uma das postagens, os espectadores foram questionados: &quot;Voc\u00ea acha que Bongani \u00e9 um &#039;Perfect 10&#039; por assumir responsabilidades e encontrar trabalho?&quot;<\/p>\n<p>As respostas foram um breve &quot;sim&quot;; no entanto, algumas capturaram o aprendizado e o desaprendizado que ocorreram. &quot;Sim, se ele deitou e fez um beb\u00ea, ele deve se levantar e ser um papai&quot;, comentou uma espectadora. Al\u00e9m disso, outra espectadora disse: &quot;Sim, xem, ele est\u00e1 come\u00e7ando a ter responsabilidade por seu filho... mesmo que eu tenha o fato de que ele n\u00e3o busca ajuda de seu pai!&quot; Isso tendo em mente que a maioria dos coment\u00e1rios foram de espectadoras que assistem \u00e0 AMAZA, semana ap\u00f3s semana, para ver o que realmente acontece com o beb\u00ea Vuyokazi e seu pai.<\/p>\n<p>A hist\u00f3ria de Bongani \u00e9 uma entre muitas, e era inten\u00e7\u00e3o dos diretores da AMAZA, Lucilla Blankenberg, Laddie Bosch e Tim Spring, garantir mudan\u00e7as comportamentais e emocionais claras quando se tratava do personagem de Bongani, especificamente ao assumir a responsabilidade por suas a\u00e7\u00f5es. Desde o Epis\u00f3dio 4, um espectro de consumidores de TV come\u00e7ou a ver o impacto da paternidade, um novo papel para Bongani, que fala sobre o trabalho e o prop\u00f3sito da campanha MenCare.<\/p>\n<p>AMAZA exibir\u00e1 seu epis\u00f3dio final em 5 de maio de 2014.<\/p>","protected":false},"excerpt":{"rendered":"<p>AMAZA \u00e9 uma s\u00e9rie dram\u00e1tica juvenil sul-africana que mostra o impacto da paternidade e aborda o prop\u00f3sito da campanha MenCare.<\/p>","protected":false},"author":7,"featured_media":521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,58,151,238,247,254],"class_list":["post-520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-amaza","tag-community-media-trust","tag-media","tag-south-africa","tag-sub-saharan-africa","tag-television","countries-south-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AMAZA incorporates the principles of MenCare in its storyline - MenCare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mencare.org\/pt\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMAZA incorporates the principles of MenCare in its storyline - MenCare\" \/>\n<meta property=\"og:description\" content=\"AMAZA is a South African youth drama TV series that shows the impact of fatherhood and speaks to the purpose of the MenCare campaign.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mencare.org\/pt\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/\" \/>\n<meta property=\"og:site_name\" content=\"MenCare\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-24T00:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/\",\"url\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/\",\"name\":\"AMAZA incorporates the principles of MenCare in its storyline - MenCare\",\"isPartOf\":{\"@id\":\"https:\/\/www.mencare.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg\",\"datePublished\":\"2014-04-24T00:00:48+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage\",\"url\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg\",\"contentUrl\":\"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg\",\"width\":550,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mencare.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AMAZA incorporates the principles of MenCare in its storyline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mencare.org\/#website\",\"url\":\"https:\/\/www.mencare.org\/\",\"name\":\"MenCare\",\"description\":\"A Global Fatherhood Campaign\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mencare.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.mencare.org\/pt\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMAZA incorporates the principles of MenCare in its storyline - MenCare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mencare.org\/pt\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/","og_locale":"pt_BR","og_type":"article","og_title":"AMAZA incorporates the principles of MenCare in its storyline - MenCare","og_description":"AMAZA is a South African youth drama TV series that shows the impact of fatherhood and speaks to the purpose of the MenCare campaign.","og_url":"https:\/\/www.mencare.org\/pt\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/","og_site_name":"MenCare","article_published_time":"2014-04-24T00:00:48+00:00","og_image":[{"width":550,"height":400,"url":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/","url":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/","name":"AMAZA incorporates the principles of MenCare in its storyline - MenCare","isPartOf":{"@id":"https:\/\/www.mencare.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage"},"image":{"@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg","datePublished":"2014-04-24T00:00:48+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#primaryimage","url":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg","contentUrl":"https:\/\/www.mencare.org\/wp-content\/uploads\/2015\/04\/Bongani-Blog-Photo.jpg","width":550,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mencare.org\/amaza-incorporates-the-principles-of-mencare-in-its-storyline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mencare.org\/"},{"@type":"ListItem","position":2,"name":"AMAZA incorporates the principles of MenCare in its storyline"}]},{"@type":"WebSite","@id":"https:\/\/www.mencare.org\/#website","url":"https:\/\/www.mencare.org\/","name":"Cuidados com os homens","description":"Uma Campanha Global de Paternidade","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mencare.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"","url":"https:\/\/www.mencare.org\/pt\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":0,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/posts\/520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/media\/521"}],"wp:attachment":[{"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/media?parent=520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/categories?post=520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mencare.org\/pt\/wp-json\/wp\/v2\/tags?post=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}